{"id":5927,"date":"2026-03-20T18:15:05","date_gmt":"2026-03-20T21:15:05","guid":{"rendered":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/?p=5927"},"modified":"2026-03-20T18:15:07","modified_gmt":"2026-03-20T21:15:07","slug":"casacor-brasilia-abre-temporada-2026","status":"publish","type":"post","link":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/","title":{"rendered":"CASACOR Bras\u00edlia abre temporada 2026"},"content":{"rendered":"\n<p>Na quarta-feira (19\/3), a Casacor Bras\u00edlia 2026 deu in\u00edcio \u00e0 nova temporada com um elegante Open House no Teatro Nacional Claudio Santoro, reunindo convidados especiais, parceiros e profissionais do setor. A\u00a0tarde foi marcada por uma apresenta\u00e7\u00e3o do Quarteto da Orquestra Sinf\u00f4nica de Bras\u00edlia, que trouxe ainda mais sofistica\u00e7\u00e3o ao encontro. Durante o evento, tamb\u00e9m foram apresentados os primeiros detalhes da 34\u00aa edi\u00e7\u00e3o da mostra, que retorna \u00e0 Casa do Candango em sintonia com o projeto de revitaliza\u00e7\u00e3o do espa\u00e7o, refor\u00e7ando o compromisso de revisitar a trajet\u00f3ria do evento enquanto projeta novas perspectivas para o futuro da arquitetura, do design e da ocupa\u00e7\u00e3o urbana na capital.<\/p>\n\n\n<div class=\"slider-wrapper\"><div class=\"slider\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5929\" src=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1024x683.jpeg\" alt=\"\" class=\"wp-image-5929\" srcset=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1024x683.jpeg 1024w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-300x200.jpeg 300w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-768x512.jpeg 768w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Margarida Kalil e Eliane Martins <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5931\" src=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-5931\" srcset=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-2-1024x683.jpeg 1024w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-2-300x200.jpeg 300w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-2-768x512.jpeg 768w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Camila de Oliveira, Renata Ciccarini e Ana Clara Ciccarini<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5928\" src=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-5928\" srcset=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1-1024x682.jpeg 1024w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1-300x200.jpeg 300w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1-768x512.jpeg 768w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1-1536x1023.jpeg 1536w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ana Clara Schick e Pedro Ariel Santana<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5933\" src=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-1024x683.jpeg\" alt=\"\" class=\"wp-image-5933\" srcset=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-1024x683.jpeg 1024w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-300x200.jpeg 300w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34-768x512.jpeg 768w, https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.34.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Geovanna Rita e Renato Paes Leme<\/figcaption><\/figure>\n<\/figure>\n<\/div>\n\t\t\t<div class=\"slider-nav\">\n\t\t\t\t<button class=\"prev\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"45\" viewBox=\"0 0 26 45\" fill=\"none\">\n\t\t\t\t<path d=\"M24.9118 0.990519C25.5461 1.62494 25.9023 2.48528 25.9023 3.38235C25.9023 4.27943 25.5461 5.13977 24.9118 5.77419L8.16559 22.5204L24.9118 39.2667C25.5281 39.9047 25.8691 40.7593 25.8614 41.6463C25.8537 42.5334 25.4979 43.3819 24.8706 44.0091C24.2434 44.6364 23.3948 44.9922 22.5078 44.9999C21.6208 45.0076 20.7662 44.6666 20.1282 44.0503L0.990082 24.9123C0.355853 24.2778 -0.000438023 23.4175 -0.000438023 22.5204C-0.000438023 21.6234 0.355853 20.763 0.990082 20.1286L20.1282 0.990519C20.7626 0.35629 21.6229 0 22.52 0C23.4171 0 24.2774 0.35629 24.9118 0.990519Z\" fill=\"white\" fill-opacity=\"0.7\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t\t<button class=\"next\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"45\" viewBox=\"0 0 26 45\" fill=\"none\">\n\t\t\t\t<path d=\"M0.99052 0.990519C0.356291 1.62494 0 2.48528 0 3.38235C0 4.27943 0.356291 5.13977 0.99052 5.77419L17.7368 22.5204L0.99052 39.2667C0.374265 39.9047 0.0332682 40.7593 0.0409763 41.6463C0.0486844 42.5334 0.40448 43.3819 1.03173 44.0091C1.65898 44.6364 2.5075 44.9922 3.39453 44.9999C4.28156 45.0076 5.13613 44.6666 5.77419 44.0503L24.9123 24.9123C25.5465 24.2778 25.9028 23.4175 25.9028 22.5204C25.9028 21.6234 25.5465 20.763 24.9123 20.1286L5.77419 0.990519C5.13977 0.35629 4.27943 0 3.38235 0C2.48528 0 1.62494 0.35629 0.99052 0.990519Z\" fill=\"white\" fill-opacity=\"0.7\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t<div class=\"slider-dots\"><\/div>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Open House re\u00fane convidados no Teatro Nacional e antecipa novidades da 34\u00aa edi\u00e7\u00e3o da mostra na capital<\/p>\n","protected":false},"author":7,"featured_media":5929,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[194,1],"tags":[9,356,198,8,950],"class_list":["post-5927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-design","category-sem-categoria","tag-brasilia","tag-casacor","tag-coquetel","tag-evento","tag-social"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CASACOR Bras\u00edlia abre temporada 2026 - Viva Bras\u00edlia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASACOR Bras\u00edlia abre temporada 2026 - Viva Bras\u00edlia\" \/>\n<meta property=\"og:description\" content=\"Open House re\u00fane convidados no Teatro Nacional e antecipa novidades da 34\u00aa edi\u00e7\u00e3o da mostra na capital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Viva Bras\u00edlia\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T21:15:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T21:15:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Campos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CASACOR Bras\u00edlia abre temporada 2026 - Viva Bras\u00edlia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"CASACOR Bras\u00edlia abre temporada 2026 - Viva Bras\u00edlia","og_description":"Open House re\u00fane convidados no Teatro Nacional e antecipa novidades da 34\u00aa edi\u00e7\u00e3o da mostra na capital","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/","og_site_name":"Viva Bras\u00edlia","article_published_time":"2026-03-20T21:15:05+00:00","article_modified_time":"2026-03-20T21:15:07+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg","type":"image\/jpeg"}],"author":"Mariana Campos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#article","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/"},"author":{"name":"Mariana Campos","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/#\/schema\/person\/018c75775aaa6ead74dde48a78ac7fa1"},"headline":"CASACOR Bras\u00edlia abre temporada 2026","datePublished":"2026-03-20T21:15:05+00:00","dateModified":"2026-03-20T21:15:07+00:00","mainEntityOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/"},"wordCount":146,"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg","keywords":["Bras\u00edlia","CasaCor","Coquetel","Evento","Social"],"articleSection":["Design"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/","name":"CASACOR Bras\u00edlia abre temporada 2026 - Viva Bras\u00edlia","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#primaryimage"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg","datePublished":"2026-03-20T21:15:05+00:00","dateModified":"2026-03-20T21:15:07+00:00","author":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/#\/schema\/person\/018c75775aaa6ead74dde48a78ac7fa1"},"breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#primaryimage","url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-content\/uploads\/sites\/4\/2026\/03\/WhatsApp-Image-2026-03-20-at-12.13.35.jpeg","width":1280,"height":854,"caption":"Margarida Kalil e Eliane Martins"},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/casacor-brasilia-abre-temporada-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/"},{"@type":"ListItem","position":2,"name":"CASACOR Bras\u00edlia abre temporada 2026"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/","name":"Viva Bras\u00edlia","description":"Coluna de estilo de vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/#\/schema\/person\/018c75775aaa6ead74dde48a78ac7fa1","name":"Mariana Campos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/97cd13271bc36c11415a45e9f8192828452de6a8c0e24857edbf96d21752260f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97cd13271bc36c11415a45e9f8192828452de6a8c0e24857edbf96d21752260f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97cd13271bc36c11415a45e9f8192828452de6a8c0e24857edbf96d21752260f?s=96&d=mm&r=g","caption":"Mariana Campos"},"description":"Colunista da Viva Bras\u00edlia, Mariana escreve e fotografa para a coluna, unindo o jornalismo escrito e fotogr\u00e1fico para mostrar que a capital \u00e9 uma cidade viva que n\u00e3o se resume apenas ao poder. Tamb\u00e9m faz a cobertura de moda para seu blog, Pliss\u00ea, e para as redes sociais do Correio. \u00c9 formada em Publicidade e Propaganda, e cursa Jornalismo.","sameAs":["http:\/\/newblogs.correiobraziliense.com\/plisse","https:\/\/www.instagram.com\/marigrigori"],"url":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/author\/marivivabrasilia\/"}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/posts\/5927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/comments?post=5927"}],"version-history":[{"count":2,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/posts\/5927\/revisions"}],"predecessor-version":[{"id":5935,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/posts\/5927\/revisions\/5935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/media\/5929"}],"wp:attachment":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/media?parent=5927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/categories?post=5927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/vivabrasilia\/wp-json\/wp\/v2\/tags?post=5927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}