{"id":2264,"date":"2026-06-24T13:18:21","date_gmt":"2026-06-24T16:18:21","guid":{"rendered":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/?p=2264"},"modified":"2026-06-24T13:18:24","modified_gmt":"2026-06-24T16:18:24","slug":"saiba-quem-pode-participar-do-programa-move-brasil","status":"publish","type":"post","link":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/","title":{"rendered":"Saiba quem pode participar do programa Move Brasil"},"content":{"rendered":"\n<p>Com investimento de R$ 30 bilh\u00f5es, o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) criou o Move Motoristas, uma linha de cr\u00e9dito que permite a taxistas e motoristas de aplicativo adquirir carros novos com taxas de juros mais reduzidas. A ideia \u00e9 renovar a frota brasileira daquele cidad\u00e3o que trabalha diariamente com o pr\u00f3prio carro.&nbsp;<\/p>\n\n\n\n<p>O financiamento \u00e9 realizado por meio de institui\u00e7\u00f5es financeiras credenciadas, sujeito \u00e0 an\u00e1lise de cr\u00e9dito. Segundo o gerente de marca da BYD Servopa, William Mendes, o financiamento tem condi\u00e7\u00f5es especiais, mas n\u00e3o vale para todos os ve\u00edculos e consumidores. \u201cO limite \u00e9 de carros novos com valor de at\u00e9 R$ 150 mil, que atendam a crit\u00e9rios de sustentabilidade e sejam provenientes de montadoras habilitadas no Programa\u201d, detalha.<\/p>\n\n\n\n<p>Para participar do Move Motoristas, \u00e9 necess\u00e1rio que o motorista de aplicativo esteja cadastrado h\u00e1 pelo menos 12 meses e tenha realizado, no m\u00ednimo, 100 corridas na plataforma durante o per\u00edodo. Para taxistas, basta ser registrado e estar em atividade. \u201cS\u00e3o precau\u00e7\u00f5es voltadas a garantir que os beneficiados sejam aqueles que utilizam o autom\u00f3vel como instrumento de trabalho, e n\u00e3o apenas como meio de transporte. Al\u00e9m disso, o solicitante precisa ter o cadastro positivo e cumprir algumas outras exig\u00eancias impostas pelo governo\u201d, completa.&nbsp;<\/p>\n\n\n\n<p>As taxas de juros podem chegar a 0,99% ao m\u00eas para homens e 0,91% ao m\u00eas para mulheres. O prazo de financiamento \u00e9 de at\u00e9 72 meses, com car\u00eancia m\u00e1xima de seis meses. Para as motoristas, o programa tamb\u00e9m permite o financiamento de equipamentos adicionais de seguran\u00e7a. A solicita\u00e7\u00e3o do cr\u00e9dito deve ser realizada na p\u00e1gina <a href=\"http:\/\/gov.br\/movebrasil\">gov.br\/movebrasil<\/a>.<\/p>\n\n\n\n<p>\u201c\u00c9 importante destacar que, enquanto o programa estiver em opera\u00e7\u00e3o, a ades\u00e3o das institui\u00e7\u00f5es financeiras e a libera\u00e7\u00e3o dos cr\u00e9ditos ocorrem de forma gradual, mediante an\u00e1lise de cr\u00e9dito. Portanto, o processo n\u00e3o \u00e9 imediato\u201d, ressalta Mendes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criado pelo governo federal para taxistas e motoristas de aplicativo, ele reserva R$ 30 bilh\u00f5es para financiar a compra de carros. Mas n\u00e3o vale para todos os modelos<\/p>\n","protected":false},"author":20,"featured_media":2265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8,40],"tags":[62,27,246,2],"class_list":["post-2264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-servicos","tag-etanol","tag-hibridos","tag-move-brasil","tag-veiculos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saiba quem pode participar do programa Move Brasil - Multieixos com Renato Ferraz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba quem pode participar do programa Move Brasil - Multieixos com Renato Ferraz\" \/>\n<meta property=\"og:description\" content=\"Criado pelo governo federal para taxistas e motoristas de aplicativo, ele reserva R$ 30 bilh\u00f5es para financiar a compra de carros. Mas n\u00e3o vale para todos os modelos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Multieixos com Renato Ferraz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100092255591956\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T16:18:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T16:18:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"559\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renato Ferraz\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba quem pode participar do programa Move Brasil - Multieixos com Renato Ferraz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Saiba quem pode participar do programa Move Brasil - Multieixos com Renato Ferraz","og_description":"Criado pelo governo federal para taxistas e motoristas de aplicativo, ele reserva R$ 30 bilh\u00f5es para financiar a compra de carros. Mas n\u00e3o vale para todos os modelos","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/","og_site_name":"Multieixos com Renato Ferraz","article_author":"https:\/\/www.facebook.com\/profile.php?id=100092255591956","article_published_time":"2026-06-24T16:18:21+00:00","article_modified_time":"2026-06-24T16:18:24+00:00","og_image":[{"width":1024,"height":559,"url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg","type":"image\/jpeg"}],"author":"Renato Ferraz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#article","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/"},"author":{"name":"Renato Ferraz","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/#\/schema\/person\/2fb466788a0749a4cd6fc2c4d89ddb15"},"headline":"Saiba quem pode participar do programa Move Brasil","datePublished":"2026-06-24T16:18:21+00:00","dateModified":"2026-06-24T16:18:24+00:00","mainEntityOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/"},"wordCount":334,"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg","keywords":["etanol","h\u00edbridos","Move Brasil","Ve\u00edculos"],"articleSection":["Carros","Servi\u00e7os"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/","name":"Saiba quem pode participar do programa Move Brasil - Multieixos com Renato Ferraz","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#primaryimage"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg","datePublished":"2026-06-24T16:18:21+00:00","dateModified":"2026-06-24T16:18:24+00:00","author":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/#\/schema\/person\/2fb466788a0749a4cd6fc2c4d89ddb15"},"breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#primaryimage","url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-content\/uploads\/sites\/6\/2026\/06\/Programa-Move-Brasil.jpg","width":1024,"height":559},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/2026\/06\/24\/saiba-quem-pode-participar-do-programa-move-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/"},{"@type":"ListItem","position":2,"name":"Saiba quem pode participar do programa Move Brasil"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/","name":"Multieixos com Renato Ferraz","description":"Aqui, voc\u00ea encontra informa\u00e7\u00f5es atualizadas sobre o mercado automotivo, tend\u00eancias de mobilidade urbana, novas solu\u00e7\u00f5es em sustentabilidade no setor de transportes e as principais mudan\u00e7as na legisla\u00e7\u00e3o de tr\u00e2nsito.","alternateName":"Blog | Multieixos com Renato Ferra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/#\/schema\/person\/2fb466788a0749a4cd6fc2c4d89ddb15","name":"Renato Ferraz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/05490fac3b629881956c1c2d33a9f5fcb406d4619aeb73f2548eb9374d66c612?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05490fac3b629881956c1c2d33a9f5fcb406d4619aeb73f2548eb9374d66c612?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05490fac3b629881956c1c2d33a9f5fcb406d4619aeb73f2548eb9374d66c612?s=96&d=mm&r=g","caption":"Renato Ferraz"},"description":"\u00c9 jornalista profissional h\u00e1 35 anos e escreve sobre carros, tr\u00e2nsito e mobilidade desde 2004, participando de centenas lan\u00e7amentos de produtos e v\u00e1rios sal\u00f5es automobil\u00edsticos globais.","sameAs":["https:\/\/www.facebook.com\/profile.php?id=100092255591956","https:\/\/www.instagram.com\/multieixos_correio\/"],"url":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/author\/renatoferraz\/"}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/posts\/2264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/comments?post=2264"}],"version-history":[{"count":1,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/posts\/2264\/revisions"}],"predecessor-version":[{"id":2266,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/posts\/2264\/revisions\/2266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/media\/2265"}],"wp:attachment":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/media?parent=2264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/categories?post=2264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/multieixos\/wp-json\/wp\/v2\/tags?post=2264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}