{"id":23,"count":1,"description":"","link":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/","name":"Izalci Lucas","slug":"izalci-lucas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Izalci Lucas | Em alta na pol\u00edtica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Izalci Lucas | Em alta na pol\u00edtica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/\" \/>\n<meta property=\"og:site_name\" content=\"Em alta na pol\u00edtica\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Izalci Lucas | Em alta na pol\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Izalci Lucas | Em alta na pol\u00edtica","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/","og_site_name":"Em alta na pol\u00edtica","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/","name":"Arquivo de Izalci Lucas | Em alta na pol\u00edtica","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#website"},"breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/tag\/izalci-lucas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/"},{"@type":"ListItem","position":2,"name":"Izalci Lucas"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/","name":"Em alta na pol\u00edtica","description":"Cobertura di\u00e1ria dos temas que dominam o debate p\u00fablico, com not\u00edcias, an\u00e1lises e bastidores da pol\u00edtica brasileira e do Distrito Federal.","publisher":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#organization","name":"Correio Braziliense","url":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#\/schema\/logo\/image\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-content\/uploads\/sites\/9\/2026\/07\/cropped-512x512-1.png","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-content\/uploads\/sites\/9\/2026\/07\/cropped-512x512-1.png","width":512,"height":512,"caption":"Correio Braziliense"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-json\/wp\/v2\/tags\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/emaltanapolitica\/wp-json\/wp\/v2\/posts?tags=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}