{"id":33202,"date":"2025-06-27T16:13:20","date_gmt":"2025-06-27T19:13:20","guid":{"rendered":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?p=33202"},"modified":"2025-06-28T10:41:20","modified_gmt":"2025-06-28T13:41:20","slug":"combinacao-perversa-contra-o-brasil","status":"publish","type":"post","link":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/","title":{"rendered":"Combina\u00e7\u00e3o perversa contra o Brasil"},"content":{"rendered":"\n<p>O embate entre Legislativo e o Executivo est\u00e1 provocando retrocessos que v\u00e3o causar despesas que cair\u00e3o no bolso de todos os brasileiros, que assistem passivos ao pa\u00eds afundando cada vez mais no atoleiro. N\u00e3o h\u00e1 inocentes nessa disputa e o eleitor precisa ficar atento a tudo o que est\u00e1 acontecendo e n\u00e3o esquecer quando for votar no ano que vem, pois a campanha eleitoral est\u00e1 em curso e h\u00e1 um jogo de vers\u00f5es que s\u00f3 confundem o pobre do cidad\u00e3o.&nbsp;<\/p>\n\n\n\n<p>O governo federal tem aumentado os gastos de forma expressiva com o discurso de que est\u00e1 beneficiando os mais pobres. Olhando para os n\u00fameros das contas p\u00fablicas, \u00e9 poss\u00edvel ver que, ao ampliar despesas obrigat\u00f3rias de forma expressiva, como as do Bolsa Fam\u00edlia, que passaram de R$ 35 bilh\u00f5es ao ano para, pelo menos, R$ 170 bilh\u00f5es, sem que cortes de outras rubricas fossem feito na mesma magnitude, o presidente Luiz In\u00e1cio Lula da Silva (PT) armou uma das maiores bombas fiscais de seu terceiro mandato. Bilh\u00f5es de reais gastos no assistencialismo sem uma porta de sa\u00edda justamente quando o pa\u00eds atinge n\u00edveis baix\u00edssimos de desemprego e o governo segue sem um bom plano para melhorar a qualidade da Educa\u00e7\u00e3o \u2013 que \u00e9 a chave para o desenvolvimento de qualquer na\u00e7\u00e3o.&nbsp;&nbsp;<\/p>\n\n\n\n<p>E o Congresso Nacional tamb\u00e9m n\u00e3o colabora. Al\u00e9m de derrubar o veto aos jabutis (emendas n\u00e3o relacionadas ao texto) da Lei das E\u00f3licas em Alto Mar (offshore) \u2013 que estimulam o uso de energia cara e poluente, de usinas movidas a carv\u00e3o e aumentam o custo da conta de luz do consumidor \u2013 aprovaram mat\u00e9ria que amplia o n\u00famero de deputados na C\u00e2mara de 513 para 531.&nbsp;<\/p>\n\n\n\n<p>\u00c9 bom lembrar que cada deputado recebe um sal\u00e1rio mensal de R$ 47,7 mil, mas com os penduricalhos como verba de gabinete, de R$ 94,3 mil; aux\u00edlio palet\u00f3 maior do que o sal\u00e1rio, de R$ 53,4 mil; aux\u00edlio moradia de R$ 22 mil; aux\u00edlio sa\u00fade de R$ 18 mil; aux\u00edlio restaurante de R$ 16,4 mil; o custo de cada cadeira sobe para R$ 341,3 mil por m\u00eas, mais ou menos. Ser\u00e1 que eles merecem receber tudo isso dos contribuintes? Eles d\u00e3o retorno para os pagadores de impostos? Eles prestam contas do que fazem? Tem deputado que nunca apresentou um \u00fanico projeto de lei, muitos nem comparecem \u00e0s vota\u00e7\u00f5es, e por a\u00ed vai\u2026<\/p>\n\n\n\n<p>E, para piorar, essa medida de aumento das cadeiras na C\u00e2mara, apesar de n\u00e3o ter um impacto fiscal como o das emendas sem transpar\u00eancia, de mais R$ 50 bilh\u00f5es \u2013 o equivalente a 25% dos gastos discricion\u00e1rios (n\u00e3o obrigat\u00f3rios) no Or\u00e7amento da Uni\u00e3o \u2013&nbsp; escancaram um fato recorrente: parlamentares n\u00e3o est\u00e3o preocupados com a transpar\u00eancia das contas p\u00fablicas e, muito menos, com a Lei de Responsabilidade Fiscal, que completou 25 anos recentemente.&nbsp;<\/p>\n\n\n\n<p>Nos pa\u00edses desenvolvidos, ministros, deputados, andam de transporte p\u00fablico ou v\u00e3o trabalhar de bicicleta. Aqui, possuem um s\u00e9quito de bajuladores que poderiam ser cortados pela metade. Ali\u00e1s, existe uma m\u00e1xima no Congresso de que se todos os servidores e parlamentares fossem trabalhar todos os dias, n\u00e3o haveria cadeira para todos sentarem, dado o n\u00famero excessivo de pessoas \u2013 que querem ampliar em vez de reduzir.&nbsp;<\/p>\n\n\n\n<p><strong>Bofetada<\/strong><\/p>\n\n\n\n<p>Portanto, aumentar o n\u00famero de parlamentares como prev\u00ea a proposta aprovada pelo Senado e pela C\u00e2mara s\u00f3 piora esse quadro que j\u00e1 \u00e9 vergonhoso e d\u00e1 uma forte bofetada na cara de cada brasileiro que presta, anualmente, as contas com o Le\u00e3o e aguarda, com sorte, alguma restitui\u00e7\u00e3o do Imposto de Renda.&nbsp;<\/p>\n\n\n\n<p>Os \u00faltimos dias mostram que tanto integrantes do Executivo quanto do Legislativo n\u00e3o fazem jus aos tributos e sal\u00e1rios pagos por todos os mais de 200 milh\u00f5es de brasileiros. Essa elite privilegiada do funcionalismo dos Tr\u00eas Poderes da Rep\u00fablica ainda possuem um monte de penduricalhos que merecem ser cortados \u2013 isso daria uma economia e tanto para os cofres da Uni\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Logo, os presidentes da C\u00e2mara, Hugo Motta, e do Senado, Davi Alcolumbre, deveriam ter vergonha de ter colocado a rubrica deles nessa proposta que vai na contram\u00e3o do discurso do Congresso reformista. Mal assumiram o mandato e j\u00e1 mostram para quem est\u00e3o legislando \u2013 para eles mesmos e o povo que se lasque.&nbsp;<\/p>\n\n\n\n<p>Mas 2026 est\u00e1 chegando. Eleitores ter\u00e3o a chance de revisarem seus votos com afinco do passado e evitar mandar novamente ao Congresso aqueles que s\u00f3 lesam a P\u00e1tria e o bolso do contribuinte. \u00c9 preciso lupa para achar um parlamentar que est\u00e1 preocupado de verdade com o equil\u00edbrio fiscal, a transpar\u00eancia das contas p\u00fablicas e n\u00e3o fica s\u00f3 fazendo postagem em rede social para ganhar curtidas.<\/p>\n\n\n\n<p>O brasileiro \u00e9 famoso por n\u00e3o saber votar direito.&nbsp;J\u00e1 passou da hora de os eleitores terem mem\u00f3ria e checarem como os parlamentares est\u00e3o votando, pois, nas \u00faltimas sess\u00f5es, falou mais alto o benef\u00edcio corporativo em detrimento ao bem da na\u00e7\u00e3o. H\u00e1 projetos importantes parados no Congresso que ajudaram a equilibrar as contas p\u00fablicas e que moralizariam o parlamento brasileiro, como o teto do funcionalismo, o fim do foro privilegiado, a reforma administrativa, entre outros&#8230; Por que n\u00e3o desengavetar?<\/p>\n\n\n\n<p>Os indignados podem assinar a peti\u00e7\u00e3o <a href=\"https:\/\/chng.it\/VgYPKd89xg\">https:\/\/chng.it\/VgYPKd89xg<\/a>. Por enquanto, havia 13 mil indignados, aproximadamente, por volta das 15h45 desta sexta-feira (27\/6).\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o<\/p>\n","protected":false},"author":10,"featured_media":33203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[2114,1952,1869,1,1953],"tags":[237,313,2113,116,2100],"class_list":["post-33202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analise","category-artigo","category-contas-publicas","category-sem-categoria","category-opiniao","tag-congresso","tag-contas-publicas","tag-desequilibrio-fiscal","tag-governo","tag-iof"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combina\u00e7\u00e3o perversa contra o Brasil - Blog da Rosana Hessel<\/title>\n<meta name=\"description\" content=\"Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combina\u00e7\u00e3o perversa contra o Brasil - Blog da Rosana Hessel\" \/>\n<meta property=\"og:description\" content=\"Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Rosana Hessel\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T19:13:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-28T13:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rosana Hessel\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combina\u00e7\u00e3o perversa contra o Brasil - Blog da Rosana Hessel","description":"Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Combina\u00e7\u00e3o perversa contra o Brasil - Blog da Rosana Hessel","og_description":"Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/","og_site_name":"Blog da Rosana Hessel","article_published_time":"2025-06-27T19:13:20+00:00","article_modified_time":"2025-06-28T13:41:20+00:00","og_image":[{"width":1170,"height":700,"url":"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp","type":"image\/webp"}],"author":"Rosana Hessel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#article","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/"},"author":{"name":"Rosana Hessel","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"headline":"Combina\u00e7\u00e3o perversa contra o Brasil","datePublished":"2025-06-27T19:13:20+00:00","dateModified":"2025-06-28T13:41:20+00:00","mainEntityOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/"},"wordCount":939,"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp","keywords":["Congresso","contas p\u00fablicas","desequil\u00edbrio fiscal","governo","IOF"],"articleSection":["An\u00e1lise","ARTIGO","Contas p\u00fablicas","Macroeconomia","OPINI\u00c3O"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/","name":"Combina\u00e7\u00e3o perversa contra o Brasil - Blog da Rosana Hessel","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#primaryimage"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp","datePublished":"2025-06-27T19:13:20+00:00","dateModified":"2025-06-28T13:41:20+00:00","author":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"description":"Embate entre Executivo e Legislativo deixa saldo negativo cada vez maior para o bolso dos brasileiros, que est\u00e3o passivos no meio dessa confus\u00e3o","breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#primaryimage","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2025\/06\/pzzb1951_2-55014101.webp","width":1170,"height":700,"caption":"Congresso Nacional\/F\u00e1bio Rodrigues Pozzebom\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/combinacao-perversa-contra-o-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/"},{"@type":"ListItem","position":2,"name":"Combina\u00e7\u00e3o perversa contra o Brasil"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/","name":"Blog da Rosana Hessel","description":"Not\u00edcias atualizadas e an\u00e1lises sobre economia. Acompanhe-nos para entender as tend\u00eancias e os impactos econ\u00f4micos que influenciam o seu dia a dia, tanto no Brasil quanto no exterior.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930","name":"Rosana Hessel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","caption":"Rosana Hessel"},"description":"Formada pela Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (PUC-SP), \u00e9 jornalista de economia desde 1995, quando passou a integrar o time da Gazeta Mercantil. Est\u00e1 sempre atr\u00e1s da boa informa\u00e7\u00e3o. Possui especializa\u00e7\u00e3o em economia pela FGV e MBA em Finan\u00e7as pela FIA-USP. Trabalha no Correio Braziliense desde 2010. Ganhou o Pr\u00eamio Esso de Jornalismo Econ\u00f4mico em 2014 e em 2015 com a equipe do Correio. Foi finalista entre os 50 jornalistas +Admirados da Imprensa de Economia, Neg\u00f3cios e Finan\u00e7as 2024, promovido pela Jornalistas&amp;Cia.","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/author\/rosanahessel\/"}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/33202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/comments?post=33202"}],"version-history":[{"count":7,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/33202\/revisions"}],"predecessor-version":[{"id":33210,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/33202\/revisions\/33210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media\/33203"}],"wp:attachment":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media?parent=33202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/categories?post=33202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/tags?post=33202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}