{"id":32286,"date":"2025-01-19T09:00:00","date_gmt":"2025-01-19T12:00:00","guid":{"rendered":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?p=32286"},"modified":"2025-01-23T18:40:48","modified_gmt":"2025-01-23T21:40:48","slug":"artigo-conflitos-acabam-em-paternalismo-de-estado","status":"publish","type":"post","link":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/","title":{"rendered":"ARTIGO: Conflitos encerram paternalismo de Estado?"},"content":{"rendered":"\n<p>Por Luiz Recena Grassi*<\/p>\n\n\n\n<p>O holand\u00eas Mark Rutte tem muito medo de ficar \u00f3rf\u00e3o na idade adulta. Um \u00f3rf\u00e3o pol\u00edtico. Nova autoridade da Organiza\u00e7\u00e3o do Tratado do Atl\u00e2ntico Norte (Otan), assumiu no final do ano passado a rosnar e a mostrar os dentes com que iria morder o l\u00edder russo Vladimir Putin, ex\u00e9rcitos e os brinquedos mort\u00edferos dele. A paz, disse ele, viria nos moldes do novo chefe dos Estados Unidos e da base aliada na Uni\u00e3o Europeia (UE). N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente. S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.<\/p>\n\n\n\n<p>As conversa\u00e7\u00f5es secretas, por serem assim, nada vazam. O pouco que transpira s\u00f3 informa novas posi\u00e7\u00f5es de desembarque de aliados. Com as tradicionais promessas de alguma verba e meios f\u00edsicos para a Ucr\u00e2nia enfrentar a crise energ\u00e9tica, que s\u00f3 piorou com os \u00faltimos ataques da R\u00fassia, com Kiev e cidades principais a sofrer mais cada semana. As principais minas de carv\u00e3o j\u00e1 est\u00e3o sob controle russo. Em Kursk, onde segura ainda sua conquista, o ex\u00e9rcito ucraniano teria recuado e deixado para tr\u00e1s 63% do territ\u00f3rio. Os russos tamb\u00e9m usaram m\u00edsseis ATACMS (americanos) em ataque a Belgorod. Por fim, ironia de p\u00e9ssimo gosto, atacaram o Sul e acertaram a cidade de \u00a0Kryvy Rih. Ali nasceu Volodymyr Zelensky. Um m\u00edssil causou 14 v\u00edtimas fatais e v\u00e1rios feridos.\u00a0<\/p>\n\n\n\n<p>Ent\u00e3o, quando Trump vier, o quadro da uni\u00e3o estar\u00e1 no m\u00ednimo confuso, desorganizado. Divididos entre o que fazer com o dinheiro russo congelado (maioria contra us\u00e1-lo, contra a tunga) e pela quest\u00e3o energ\u00e9tica, as posi\u00e7\u00f5es s\u00e3o d\u00edspares. Orban, da Hungria, criticou as \u00faltimas decis\u00f5es dos EUA em boicotar a R\u00fassia no mercado energ\u00e9tico. S\u00f3 aumentou os problemas. Pediu o fim imediato das san\u00e7\u00f5es contra o Kremlin. Olaf Scholz, da Alemanha, revelou um c\u00e2ndido desejo de que Trump n\u00e3o corte todas armas para Kiev. Fico, da Eslov\u00e1quia, deixou claro precisar da R\u00fassia para n\u00e3o passar frio. Marcelo Rebelo, presidente de Portugal, torce para que os russos n\u00e3o devorem os ucranianos. Rom\u00eania e Bulg\u00e1ria est\u00e3o sob forte ataque dos partidos pr\u00f3-R\u00fassia. At\u00e9 a \u00c1ustria, antes um pouco fora da curva da discuss\u00e3o, acompanhando mais a maioria na UE, perdeu espa\u00e7o interno, cedeu e seu governo vai negociar com o partido pr\u00f3-R\u00fassia. A Pol\u00f4nia tenta todas as a\u00e7\u00f5es poss\u00edveis para arranjar mais armas. Para si e para a Ucr\u00e2nia. A Inglaterra fechou um acordo-quadro para durar cem anos e atuar em muitas frentes em ajuda \u00e0 Ucr\u00e2nia. O velho faro ingl\u00eas sentiu o cheiro forte da reconstru\u00e7\u00e3o, que vai requerer tempo e muitos bilh\u00f5es de d\u00f3lares. Pode haver corrida por obras de Israel\/Gaza, mas l\u00e1 o volume de verba requerida \u00e9 bem menor. <\/p>\n\n\n\n<p>Ent\u00e3o: Welcome Mr. Trump!\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p>O CORREIO SABE PORQUE VIU. <\/p>\n\n\n\n<p>Estava l\u00e1. Antes mesmo da Uni\u00e3o Sovi\u00e9tica dar seus \u00faltimos suspiros muitas coisas diferentes aconteceram para seus habitantes. Desde a descriminaliza\u00e7\u00e3o da posse do d\u00f3lar e outras moedas at\u00e9 as invers\u00f5es em pequenos neg\u00f3cios, associadas a parceiros de outros pa\u00edses. Da\u00ed para o mercado de trabalho n\u00e3o demorou muito, mas manteve nas alturas os \u00edndices de novidade, surpresa e at\u00e9 de espanto por parte dos velhos e jovens sovi\u00e9ticos, n\u00e3o s\u00f3 pelo fato de, agora, perderem o t\u00edtulo de \u201cTovarich\u201d (camarada) e ganhar o t\u00edtulo de \u201cTchilaviek\u201d (cidad\u00e3o). Come\u00e7ou com o aluguel compartilhado: russos cediam parte de moradias para estrangeiros em busca de melhor aluguel para morar ou instalar escrit\u00f3rios comerciais. Com clientes de r\u00e1dio no Brasil e outros pa\u00edses, aluguei duas horas por dia uma sala em um pequeno e especializado museu no centro de Moscou. S\u00f3 abria ao p\u00fablico nos fins de semana. A desvaloriza\u00e7\u00e3o do sal\u00e1rio funcional estimulava as duas \u00fanicas funcion\u00e1rias. Pagava em d\u00f3lares. Elas fechavam os olhos para receber e dividir. Milhares de neg\u00f3cios como esse foram feitos. Polichinelo mantinha seu segredo e a mulher de C\u00e9sar refor\u00e7ava o discurso de honestidade.<\/p>\n\n\n\n<p>As coisas s\u00f3 se complicaram quando chegaram as m\u00e9dias e grandes empresas e foi preciso contratos formais para ingresso no mercado. A diferen\u00e7a de cultura falou mais alto: os sovi\u00e9ticos tinham turnos com mais folgas e bancos de pessoal reserva. Afinal,\u00a0 o pilar te\u00f3rico do velho regime era a classe trabalhadora. Quanto mais selvagem, mais dif\u00edcil era a postura do capital na hora da negocia\u00e7\u00e3o. Sem gritar, mas com argumentos imbat\u00edveis, uma jovem e simp\u00e1tica russa, j\u00e1 gerente de um hotel em S\u00e3o Petersburgo, disse-me claramente: \u201cpara entrar aqui ele dever\u00e3o pagar nossas exig\u00eancias; n\u00e3o ser\u00e1 como na terra deles, onde daqui para baixo (sinalizou com as m\u00e3os nos quadris) ele acham que podem e fazem tudo. No nosso, n\u00e3o!\u201d. Se Mark Rutte est\u00e1 com medo de que os europeus aprendam russo, \u00e9 bom prestar aten\u00e7\u00e3o, antes, na cultura do pa\u00eds.<\/p>\n\n\n\n<p>*<em>O jornalista foi, por muitos anos, correspondente do\u00a0<\/em><strong><em>Correio Braziliense<\/em><\/strong><em>\u00a0em Moscou<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.<\/p>\n","protected":false},"author":10,"featured_media":31810,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1953],"tags":[128,307,132,134],"class_list":["post-32286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniao","tag-guerra","tag-otan","tag-russia","tag-ucrania"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARTIGO: Conflitos encerram paternalismo de Estado? - Blog da Rosana Hessel<\/title>\n<meta name=\"description\" content=\"N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARTIGO: Conflitos encerram paternalismo de Estado? - Blog da Rosana Hessel\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Rosana Hessel\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-19T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T21:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosana Hessel\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARTIGO: Conflitos encerram paternalismo de Estado? - Blog da Rosana Hessel","description":"N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/","og_locale":"pt_BR","og_type":"article","og_title":"ARTIGO: Conflitos encerram paternalismo de Estado? - Blog da Rosana Hessel","og_description":"N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/","og_site_name":"Blog da Rosana Hessel","article_published_time":"2025-01-19T12:00:00+00:00","article_modified_time":"2025-01-23T21:40:48+00:00","og_image":[{"width":1600,"height":1066,"url":"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg","type":"image\/jpeg"}],"author":"Rosana Hessel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#article","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/"},"author":{"name":"Rosana Hessel","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"headline":"ARTIGO: Conflitos encerram paternalismo de Estado?","datePublished":"2025-01-19T12:00:00+00:00","dateModified":"2025-01-23T21:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/"},"wordCount":916,"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg","keywords":["guerra","Otan","R\u00fassia","Ucr\u00e2nia"],"articleSection":["OPINI\u00c3O"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/","name":"ARTIGO: Conflitos encerram paternalismo de Estado? - Blog da Rosana Hessel","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#primaryimage"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg","datePublished":"2025-01-19T12:00:00+00:00","dateModified":"2025-01-23T21:40:48+00:00","author":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"description":"N\u00e3o foi o que se viu. A elei\u00e7\u00e3o de Donald Trump foi o primeiro sinal do desmanche iminente (da Otan). S\u00f3lido sinal, ao mandar imediatamente a Moscou um negociador, ainda que sem poderes formais.","breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#primaryimage","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/11\/TrumpAFP.jpg","width":1600,"height":1066,"caption":"Trump Credito:AFPIMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/artigo-conflitos-acabam-em-paternalismo-de-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/"},{"@type":"ListItem","position":2,"name":"ARTIGO: Conflitos encerram paternalismo de Estado?"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/","name":"Blog da Rosana Hessel","description":"Not\u00edcias atualizadas e an\u00e1lises sobre economia. Acompanhe-nos para entender as tend\u00eancias e os impactos econ\u00f4micos que influenciam o seu dia a dia, tanto no Brasil quanto no exterior.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930","name":"Rosana Hessel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","caption":"Rosana Hessel"},"description":"Formada pela Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (PUC-SP), \u00e9 jornalista de economia desde 1995, quando passou a integrar o time da Gazeta Mercantil. Est\u00e1 sempre atr\u00e1s da boa informa\u00e7\u00e3o. Possui especializa\u00e7\u00e3o em economia pela FGV e MBA em Finan\u00e7as pela FIA-USP. Trabalha no Correio Braziliense desde 2010. Ganhou o Pr\u00eamio Esso de Jornalismo Econ\u00f4mico em 2014 e em 2015 com a equipe do Correio. Foi finalista entre os 50 jornalistas +Admirados da Imprensa de Economia, Neg\u00f3cios e Finan\u00e7as 2024, promovido pela Jornalistas&amp;Cia.","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/author\/rosanahessel\/"}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/32286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/comments?post=32286"}],"version-history":[{"count":6,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/32286\/revisions"}],"predecessor-version":[{"id":32296,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/32286\/revisions\/32296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media\/31810"}],"wp:attachment":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media?parent=32286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/categories?post=32286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/tags?post=32286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}