{"id":31903,"date":"2024-11-28T22:17:51","date_gmt":"2024-11-29T01:17:51","guid":{"rendered":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?p=31903"},"modified":"2024-11-28T22:19:04","modified_gmt":"2024-11-29T01:19:04","slug":"em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado","status":"publish","type":"post","link":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/","title":{"rendered":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado"},"content":{"rendered":"\n<p>A rea\u00e7\u00e3o negativa do mercado financeiro ao an\u00fancio atabalhoado do governo sobre o pacote de cortes de R$ 70 bilh\u00f5es em dois anos fez com o d\u00f3lar bater dois recordes seguidos, encostando em R$ 6. Enquanto isso, a Bolsa de Valores de S\u00e3o Paulo (B3), acumulou, nesta sexta-feira (28\/11), mais de R$ 170 bilh\u00f5es em perdas em valor de mercado, conforme dados da consultoria Elos Ayta.<\/p>\n\n\n\n<p>\u201dO valor de mercado das empresas listadas na B3 encolheu R$ 172,9 bilh\u00f5es nos dois \u00faltimos preg\u00f5es, com destaque para as perdas em grandes bancos e na Petrobras\u201d, destacou Einar Rivero, s\u00f3cio fundador da consultoria.\u00a0 Na avalia\u00e7\u00e3o do analista, a divulga\u00e7\u00e3o do pacote fiscal foi mal recebida pelo mercado, \u201cgerando incerteza sobre o impacto nas contas p\u00fablicas e no ambiente de neg\u00f3cios, contribuindo para a queda da B3\u201d.\u00a0<\/p>\n\n\n\n<p><strong>Queda acumulada<\/strong><\/p>\n\n\n\n<p>O \u00cdndice Bovespa (IBovespa), principal indicador da B3, acumulou queda de 4,09% nos dois \u00faltimos preg\u00f5es de novembro, enquanto o d\u00f3lar Ptax valorizou 3,24%. \u201cEsse cen\u00e1rio, combinado com a divulga\u00e7\u00e3o de um pacote fiscal na noite de 27 de novembro, gerou forte rea\u00e7\u00e3o negativa no mercado\u201d, explicou. \u201cA valoriza\u00e7\u00e3o do d\u00f3lar, somada \u00e0 incerteza fiscal, pode ter aumentado a avers\u00e3o ao risco entre investidores\u201d, avaliou Rivero.<\/p>\n\n\n\n<p>Segundo o analista, o setor financeiro foi o mais afetado na mesma base de compara\u00e7\u00e3o, com o Ita\u00fa Unibanco liderando as perdas (-R$ 17,6 bilh\u00f5es). Em seguida, os bancos BTG Pactual e Bradesco, com perdas de R$ 14,5 bilh\u00f5es e R$ 9,3 bilh\u00f5es. \u201cO pessimismo pode estar ligado a temores fiscais e ao impacto da alta do d\u00f3lar em institui\u00e7\u00f5es financeiras com exposi\u00e7\u00e3o cambial ou depend\u00eancia de cr\u00e9dito\u201d, afirmou.<\/p>\n\n\n\n<p>A Petrobras perdeu R$ 9,4 bilh\u00f5es no mesmo per\u00edodo, refletindo o impacto direto das preocupa\u00e7\u00f5es com o pacote fiscal do governo. De acordo com Rivero, a falta de confian\u00e7a na nova proposta pode estar afetando as expectativas de crescimento e estabilidade econ\u00f4mica, especialmente no setor de commodities\u201d.<\/p>\n\n\n\n<p><strong>Pacote pol\u00eamico<\/strong> <strong>e recheado de cr\u00edticas<\/strong><\/p>\n\n\n\n<p>Ao anunciar o pacote de corte de despesas, o ministro da Fazenda, Fernando Haddad, tamb\u00e9m adiantou o an\u00fancio de uma ren\u00fancia fiscal que pode chegar a R$ 40 bilh\u00f5es ou R$ 50 bilh\u00f5es com a isen\u00e7\u00e3o do Imposto de Renda para quem ganha at\u00e9 R$ 5 mil. Isso aumentou a desconfian\u00e7a do mercado e fez o d\u00f3lar subir e bater um segundo recorde seguido desde o in\u00edcio do Plano Real e a Bolsa acumular perdas e ficar abaixo de 125 mil pontos.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m de agentes financeiros, entidades do terceiro setor tamb\u00e9m criticaram o pacote. Para o Centro de Lideran\u00e7a P\u00fablica (CLP), as iniciativas anunciadas pelo ministro \u201cs\u00e3o insuficientes para promover ajuste fiscal efetivo\u201d. Em nota t\u00e9cnica, institui\u00e7\u00e3o informou que, &#8220;para resolver a quest\u00e3o, seriam necess\u00e1rias reformas estruturais profundas, tanto no sistema tribut\u00e1rio quanto previdenci\u00e1rio, para garantir a sustentabilidade das contas p\u00fablicas e fomentar um ambiente prop\u00edcio ao desenvolvimento econ\u00f4mico e social do pa\u00eds&#8221;.<\/p>\n\n\n\n<p>\u201cNo que diz respeito \u00e0 aposentadoria dos militares, embora algumas altera\u00e7\u00f5es tenham sido introduzidas, como o aumento progressivo da idade m\u00ednima para a transfer\u00eancia \u00e0 reserva remunerada e mudan\u00e7as nas regras de pens\u00e3o, ainda h\u00e1 timidez frente \u00e0 gravidade do d\u00e9ficit. A Previd\u00eancia militar, que consome R$ 59 bilh\u00f5es anuais ou 0,5% do PIB (Produto Interno Bruto), permanece sem uma base contributiva s\u00f3lida e com regras que incentivam a aposentadoria precoce\u201d, destacou o comunicado..<\/p>\n\n\n\n<p>Ainda de acordo com a nota t\u00e9cnica do CLP, entre as a\u00e7\u00f5es que poderiam contribuir para reduzir esses gastos previdenci\u00e1rios e assistenciais, destaca-se a necessidade de uma segunda reforma da Previd\u00eancia, focando em conter os gastos com o Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC) e a aposentadoria rural. \u201cA implementa\u00e7\u00e3o de um gatilho que ajuste a idade m\u00ednima de aposentadoria com base no aumento da expectativa de vida tamb\u00e9m seria essencial para garantir a sustentabilidade do sistema previdenci\u00e1rio a longo prazo\u201d, acrescentou o comunicado.<\/p>\n\n\n\n<p>De acordo com Nathalie Beghin, integrante do colegiado de gest\u00e3o do Instituto de Estudos Socioecon\u00f4micos (Inesc), embora tenha havido um esfor\u00e7o do governo em distribuir os encargos fiscais, \u201cas pessoas de baixa renda ainda continuam sendo as mais prejudicadas, quando deveriam ser beneficiadas devido \u00e0 significativa d\u00edvida social, ambiental e clim\u00e1tica do pa\u00eds\u201d. <\/p>\n\n\n\n<p>Segundo ela, o avan\u00e7o estaria na isen\u00e7\u00e3o do Imposto de Renda para quem ganha at\u00e9 R$ 5 mil, um benef\u00edcio que pode perder o efeito dada a austeridade da medida que afeta desproporcionalmente os mais pobres. Isso porque, mesmo com o aumento real das receitas, o governo insiste em cortar gastos para controlar o crescimento das despesas obrigat\u00f3rias, o que mant\u00e9m a incerteza sobre a renda das fam\u00edlias de baixa renda.<\/p>\n\n\n\n<p>Outras cr\u00edticas apontadas na nota do Inesc dizem respeito \u00e0 vincula\u00e7\u00e3o do aumento real do sal\u00e1rio m\u00ednimo \u00e0 regra fiscal, \u00e0 redu\u00e7\u00e3o progressiva do teto para acesso ao abono salarial, e \u00e0s novas barreiras para o acesso ao BPC, porque essas e outras iniciativas &#8220;podem comprometer o financiamento de pol\u00edticas sociais essenciais&#8221;. <\/p>\n\n\n\n<p>A entidade tamb\u00e9m criticou o fato de o governo n\u00e3o mexer em benef\u00edcios empresariais no pacote. \u201cH\u00e1 limites potenciais ao crescimento de benef\u00edcios fiscais no futuro, mas n\u00e3o h\u00e1 revis\u00e3o dos atuais: se houver deficit prim\u00e1rio de 2025 em diante, no exerc\u00edcio seguinte \u00e0 apura\u00e7\u00e3o do deficit fica vedada a cria\u00e7\u00e3o, majora\u00e7\u00e3o ou prorroga\u00e7\u00e3o de benef\u00edcios tribut\u00e1rios. Na realidade, n\u00e3o h\u00e1 qualquer proposta de avalia\u00e7\u00e3o ou revis\u00e3o das benesses tribut\u00e1rias destinadas ao setor empresarial hoje\u201d, destacou o texto. \u201cSabe-se que boa parte delas \u00e9 ineficiente, este \u00e9 o caso, por exemplo, das ren\u00fancias fiscais do setor de \u00f3leo e g\u00e1s, que foram da ordem de R$ 66 bilh\u00f5es em 2023, de acordo com estudo do Inesc. S\u00e3o vultosos recursos que irrigam um setor que faz mal \u00e0 sa\u00fade do planeta\u201d, acrescentou o documento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es  em dois preg\u00f5es<\/p>\n","protected":false},"author":10,"featured_media":30912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1869,1],"tags":[1237,35,313,1973,1985,1861,36,116,847,1981],"class_list":["post-31903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contas-publicas","category-sem-categoria","tag-b3","tag-bolsa","tag-contas-publicas","tag-corte-de-gastos","tag-criticas-2","tag-despesas","tag-dolar","tag-governo","tag-impacto","tag-pacote-fiscal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado - Blog da Rosana Hessel<\/title>\n<meta name=\"description\" content=\"Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es em dois preg\u00f5es\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado - Blog da Rosana Hessel\" \/>\n<meta property=\"og:description\" content=\"Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es em dois preg\u00f5es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Rosana Hessel\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-29T01:17:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T01:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosana Hessel\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado - Blog da Rosana Hessel","description":"Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es em dois preg\u00f5es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/","og_locale":"pt_BR","og_type":"article","og_title":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado - Blog da Rosana Hessel","og_description":"Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es em dois preg\u00f5es","og_url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/","og_site_name":"Blog da Rosana Hessel","article_published_time":"2024-11-29T01:17:51+00:00","article_modified_time":"2024-11-29T01:19:04+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg","type":"image\/jpeg"}],"author":"Rosana Hessel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#article","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/"},"author":{"name":"Rosana Hessel","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"headline":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado","datePublished":"2024-11-29T01:17:51+00:00","dateModified":"2024-11-29T01:19:04+00:00","mainEntityOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/"},"wordCount":1044,"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg","keywords":["B3","bolsa","contas p\u00fablicas","corte de gastos","cr\u00edticas","despesas","d\u00f3lar","governo","impacto","pacote fiscal"],"articleSection":["Contas p\u00fablicas","Macroeconomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/","name":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado - Blog da Rosana Hessel","isPartOf":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#primaryimage"},"image":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg","datePublished":"2024-11-29T01:17:51+00:00","dateModified":"2024-11-29T01:19:04+00:00","author":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930"},"description":"Rea\u00e7\u00e3o negativa do mercado ao pacote de corte de gastos do governo faz empresas listadas na B3 perderem mais de R$ 170 bilh\u00f5es em dois preg\u00f5es","breadcrumb":{"@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#primaryimage","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg","contentUrl":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-content\/uploads\/sites\/5\/2024\/06\/CBIFOT010620211080bolsa.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/em-dois-pregoes-bolsa-perde-r-1729-bilhoes-em-valor-de-mercado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/"},{"@type":"ListItem","position":2,"name":"Em dois preg\u00f5es, Bolsa perde R$ 172,9 bilh\u00f5es em valor de mercado"}]},{"@type":"WebSite","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#website","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/","name":"Blog da Rosana Hessel","description":"Not\u00edcias atualizadas e an\u00e1lises sobre economia. Acompanhe-nos para entender as tend\u00eancias e os impactos econ\u00f4micos que influenciam o seu dia a dia, tanto no Brasil quanto no exterior.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/#\/schema\/person\/824cb3c631cf0d4056f75ca02599a930","name":"Rosana Hessel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe780cf1839cf10cd6d682fb080611e0d2a459b64be8a8781778109777fbcfd3?s=96&d=mm&r=g","caption":"Rosana Hessel"},"description":"Formada pela Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (PUC-SP), \u00e9 jornalista de economia desde 1995, quando passou a integrar o time da Gazeta Mercantil. Est\u00e1 sempre atr\u00e1s da boa informa\u00e7\u00e3o. Possui especializa\u00e7\u00e3o em economia pela FGV e MBA em Finan\u00e7as pela FIA-USP. Trabalha no Correio Braziliense desde 2010. Ganhou o Pr\u00eamio Esso de Jornalismo Econ\u00f4mico em 2014 e em 2015 com a equipe do Correio. Foi finalista entre os 50 jornalistas +Admirados da Imprensa de Economia, Neg\u00f3cios e Finan\u00e7as 2024, promovido pela Jornalistas&amp;Cia.","url":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/author\/rosanahessel\/"}]}},"_links":{"self":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/31903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/comments?post=31903"}],"version-history":[{"count":8,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/31903\/revisions"}],"predecessor-version":[{"id":31911,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/posts\/31903\/revisions\/31911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media\/30912"}],"wp:attachment":[{"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/media?parent=31903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/categories?post=31903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newblogs.correiobraziliense.com.br\/blog-da-rosana-hessel\/wp-json\/wp\/v2\/tags?post=31903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}